{"id":706,"date":"2018-09-24T09:46:45","date_gmt":"2018-09-24T09:46:45","guid":{"rendered":"https:\/\/www.music-scores.com\/blog\/?p=706"},"modified":"2021-04-19T08:16:03","modified_gmt":"2021-04-19T08:16:03","slug":"recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd","status":"publish","type":"post","link":"https:\/\/www.music-scores.com\/blog\/recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd\/","title":{"rendered":"Recently Added Sheet Music &#8211; 21 September 2018 (Grieg: Op.12, No.4: Fairy Dance Cont&#8217;d \/ &#038; No.5: Popular Melody)"},"content":{"rendered":"<p>Hello<\/p>\n<p>It&#8217;s nearly October and the temperature has certainly dropped today.\u00a0 However, the sun is shining and the squirrels are hopping across the garden&#8230;<\/p>\n<p>This week we have\u00a0seven new arrangements from from <strong>Grieg&#8217;s Op, 12,<\/strong>\u00a0to add to the twenty five added last week.<\/p>\n<ul>\n<li><strong>Grieg: Op.12, No.5: Popular Melody<br \/>\n<\/strong><a href=\"https:\/\/www.music-scores.com\/midi.php?sheetmusic=Grieg_Op12_No5_Popular_Melody_String4\">String Quartet<\/a><br \/>\n<a href=\"https:\/\/www.music-scores.com\/midi.php?sheetmusic=Grieg_Op12_No5_Popular_Melody_Wind4\">Wind Quartet<\/a><br \/>\n<a href=\"https:\/\/www.music-scores.com\/midi.php?sheetmusic=Grieg_Op12_No5_Popular_Melody_Brass4\">Brass Quartet<\/a><\/li>\n<\/ul>\n<ul>\n<li><strong>Grieg: Op.12, No.4: Fairy Dance<\/strong><br \/>\n<a href=\"https:\/\/www.music-scores.com\/midi.php?sheetmusic=Grieg_Op12_No4_Fairy_Dance_String5\">Violin Quintet<\/a><br \/>\n<a href=\"https:\/\/www.music-scores.com\/midi.php?sheetmusic=Grieg_Op12_No4_Fairy_Dance_Sax5\">Saxophone Quintet<\/a><br \/>\n<a href=\"https:\/\/www.music-scores.com\/midi.php?sheetmusic=Grieg_Op12_No4_Fairy_Dance_Flute5\">Flute Quintet<\/a><br \/>\n<a href=\"https:\/\/www.music-scores.com\/midi.php?sheetmusic=Grieg_Op12_No4_Fairy_Dance_Brass5\">Brass Quintet<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Hello It&#8217;s nearly October and the temperature has certainly dropped today.\u00a0 However, the sun is shining and the squirrels are hopping across the garden&#8230; This week we have\u00a0seven new arrangements from from Grieg&#8217;s Op, 12,\u00a0to add to the twenty five added last week. Grieg: Op.12, No.5: Popular Melody String Quartet Wind Quartet Brass Quartet Grieg:&hellip;&nbsp;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-706","post","type-post","status-publish","format-standard","hentry","category-recently-added-sheet-music"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Recently Added Sheet Music - 21 September 2018 (Grieg: Op.12, No.4: Fairy Dance Cont&#039;d \/ &amp; No.5: Popular Melody) -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.music-scores.com\/blog\/recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recently Added Sheet Music - 21 September 2018 (Grieg: Op.12, No.4: Fairy Dance Cont&#039;d \/ &amp; No.5: Popular Melody)\" \/>\n<meta property=\"og:description\" content=\"Hello It&#8217;s nearly October and the temperature has certainly dropped today.\u00a0 However, the sun is shining and the squirrels are hopping across the garden&#8230; This week we have\u00a0seven new arrangements from from Grieg&#8217;s Op, 12,\u00a0to add to the twenty five added last week. Grieg: Op.12, No.5: Popular Melody String Quartet Wind Quartet Brass Quartet Grieg:&hellip;&nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.music-scores.com\/blog\/recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/musicscorescom\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-24T09:46:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-19T08:16:03+00:00\" \/>\n<meta name=\"author\" content=\"Marie Tilley\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@musicscores\" \/>\n<meta name=\"twitter:site\" content=\"@musicscores\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marie Tilley\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd\\\/\"},\"author\":{\"name\":\"Marie Tilley\",\"@id\":\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/#\\\/schema\\\/person\\\/1cdfb00b4dc3e35b85808a1cc040a308\"},\"headline\":\"Recently Added Sheet Music &#8211; 21 September 2018 (Grieg: Op.12, No.4: Fairy Dance Cont&#8217;d \\\/ &#038; No.5: Popular Melody)\",\"datePublished\":\"2018-09-24T09:46:45+00:00\",\"dateModified\":\"2021-04-19T08:16:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd\\\/\"},\"wordCount\":86,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/#organization\"},\"articleSection\":[\"Recently Added Sheet Music\"],\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd\\\/\",\"url\":\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd\\\/\",\"name\":\"Recently Added Sheet Music - 21 September 2018 (Grieg: Op.12, No.4: Fairy Dance Cont'd \\\/ & No.5: Popular Melody) -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/#website\"},\"datePublished\":\"2018-09-24T09:46:45+00:00\",\"dateModified\":\"2021-04-19T08:16:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd\\\/#breadcrumb\"},\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recently Added Sheet Music &#8211; 21 September 2018 (Grieg: Op.12, No.4: Fairy Dance Cont&#8217;d \\\/ &#038; No.5: Popular Melody)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/\",\"name\":\"Music Scores Blog\",\"description\":\"\u00a0 \u00a0 \",\"publisher\":{\"@id\":\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/#organization\",\"name\":\"Music-Scores.com\",\"url\":\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/ms-logo-adjust.png\",\"contentUrl\":\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/ms-logo-adjust.png\",\"width\":2538,\"height\":2246,\"caption\":\"Music-Scores.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/musicscorescom\\\/\",\"https:\\\/\\\/x.com\\\/musicscores\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/#\\\/schema\\\/person\\\/1cdfb00b4dc3e35b85808a1cc040a308\",\"name\":\"Marie Tilley\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8126757afa597e86b8f7af57b5c9146b997ee573264be59b7c4bbbead3650c29?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8126757afa597e86b8f7af57b5c9146b997ee573264be59b7c4bbbead3650c29?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8126757afa597e86b8f7af57b5c9146b997ee573264be59b7c4bbbead3650c29?s=96&d=identicon&r=g\",\"caption\":\"Marie Tilley\"},\"url\":\"https:\\\/\\\/www.music-scores.com\\\/blog\\\/author\\\/marie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Recently Added Sheet Music - 21 September 2018 (Grieg: Op.12, No.4: Fairy Dance Cont'd \/ & No.5: Popular Melody) -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.music-scores.com\/blog\/recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd\/","og_locale":"en_US","og_type":"article","og_title":"Recently Added Sheet Music - 21 September 2018 (Grieg: Op.12, No.4: Fairy Dance Cont'd \/ & No.5: Popular Melody)","og_description":"Hello It&#8217;s nearly October and the temperature has certainly dropped today.\u00a0 However, the sun is shining and the squirrels are hopping across the garden&#8230; This week we have\u00a0seven new arrangements from from Grieg&#8217;s Op, 12,\u00a0to add to the twenty five added last week. Grieg: Op.12, No.5: Popular Melody String Quartet Wind Quartet Brass Quartet Grieg:&hellip;&nbsp;","og_url":"https:\/\/www.music-scores.com\/blog\/recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd\/","article_publisher":"https:\/\/www.facebook.com\/musicscorescom\/","article_published_time":"2018-09-24T09:46:45+00:00","article_modified_time":"2021-04-19T08:16:03+00:00","author":"Marie Tilley","twitter_card":"summary_large_image","twitter_creator":"@musicscores","twitter_site":"@musicscores","twitter_misc":{"Written by":"Marie Tilley","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.music-scores.com\/blog\/recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd\/#article","isPartOf":{"@id":"https:\/\/www.music-scores.com\/blog\/recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd\/"},"author":{"name":"Marie Tilley","@id":"https:\/\/www.music-scores.com\/blog\/#\/schema\/person\/1cdfb00b4dc3e35b85808a1cc040a308"},"headline":"Recently Added Sheet Music &#8211; 21 September 2018 (Grieg: Op.12, No.4: Fairy Dance Cont&#8217;d \/ &#038; No.5: Popular Melody)","datePublished":"2018-09-24T09:46:45+00:00","dateModified":"2021-04-19T08:16:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.music-scores.com\/blog\/recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd\/"},"wordCount":86,"commentCount":0,"publisher":{"@id":"https:\/\/www.music-scores.com\/blog\/#organization"},"articleSection":["Recently Added Sheet Music"],"inLanguage":"en","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.music-scores.com\/blog\/recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.music-scores.com\/blog\/recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd\/","url":"https:\/\/www.music-scores.com\/blog\/recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd\/","name":"Recently Added Sheet Music - 21 September 2018 (Grieg: Op.12, No.4: Fairy Dance Cont'd \/ & No.5: Popular Melody) -","isPartOf":{"@id":"https:\/\/www.music-scores.com\/blog\/#website"},"datePublished":"2018-09-24T09:46:45+00:00","dateModified":"2021-04-19T08:16:03+00:00","breadcrumb":{"@id":"https:\/\/www.music-scores.com\/blog\/recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd\/#breadcrumb"},"inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.music-scores.com\/blog\/recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.music-scores.com\/blog\/recently-added-sheet-music-21-september-2018-greig-op-12-no-4-fairy-dance-contd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.music-scores.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Recently Added Sheet Music &#8211; 21 September 2018 (Grieg: Op.12, No.4: Fairy Dance Cont&#8217;d \/ &#038; No.5: Popular Melody)"}]},{"@type":"WebSite","@id":"https:\/\/www.music-scores.com\/blog\/#website","url":"https:\/\/www.music-scores.com\/blog\/","name":"Music Scores Blog","description":"\u00a0 \u00a0 ","publisher":{"@id":"https:\/\/www.music-scores.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.music-scores.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"},{"@type":"Organization","@id":"https:\/\/www.music-scores.com\/blog\/#organization","name":"Music-Scores.com","url":"https:\/\/www.music-scores.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/www.music-scores.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.music-scores.com\/blog\/wp-content\/uploads\/2017\/11\/ms-logo-adjust.png","contentUrl":"https:\/\/www.music-scores.com\/blog\/wp-content\/uploads\/2017\/11\/ms-logo-adjust.png","width":2538,"height":2246,"caption":"Music-Scores.com"},"image":{"@id":"https:\/\/www.music-scores.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/musicscorescom\/","https:\/\/x.com\/musicscores"]},{"@type":"Person","@id":"https:\/\/www.music-scores.com\/blog\/#\/schema\/person\/1cdfb00b4dc3e35b85808a1cc040a308","name":"Marie Tilley","image":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/secure.gravatar.com\/avatar\/8126757afa597e86b8f7af57b5c9146b997ee573264be59b7c4bbbead3650c29?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8126757afa597e86b8f7af57b5c9146b997ee573264be59b7c4bbbead3650c29?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8126757afa597e86b8f7af57b5c9146b997ee573264be59b7c4bbbead3650c29?s=96&d=identicon&r=g","caption":"Marie Tilley"},"url":"https:\/\/www.music-scores.com\/blog\/author\/marie\/"}]}},"_links":{"self":[{"href":"https:\/\/www.music-scores.com\/blog\/wp-json\/wp\/v2\/posts\/706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.music-scores.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.music-scores.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.music-scores.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.music-scores.com\/blog\/wp-json\/wp\/v2\/comments?post=706"}],"version-history":[{"count":6,"href":"https:\/\/www.music-scores.com\/blog\/wp-json\/wp\/v2\/posts\/706\/revisions"}],"predecessor-version":[{"id":4156,"href":"https:\/\/www.music-scores.com\/blog\/wp-json\/wp\/v2\/posts\/706\/revisions\/4156"}],"wp:attachment":[{"href":"https:\/\/www.music-scores.com\/blog\/wp-json\/wp\/v2\/media?parent=706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.music-scores.com\/blog\/wp-json\/wp\/v2\/categories?post=706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.music-scores.com\/blog\/wp-json\/wp\/v2\/tags?post=706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}